{"id":5075,"date":"2025-06-17T02:34:33","date_gmt":"2025-06-17T02:34:33","guid":{"rendered":"https:\/\/banxa.com\/sikayetler\/"},"modified":"2026-04-23T19:58:06","modified_gmt":"2026-04-23T19:58:06","slug":"sikayetler","status":"publish","type":"page","link":"https:\/\/banxa.com\/tr\/sikayetler\/","title":{"rendered":"\u015eikayetler"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5075\" class=\"elementor elementor-5075 elementor-3467\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d18a11 e-flex e-con-boxed e-con e-parent\" data-id=\"0d18a11\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cb73944 e-con-full e-flex e-con e-child\" data-id=\"cb73944\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-adeb42d crosshtml elementor-widget elementor-widget-html\" data-id=\"adeb42d\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"t0\" data-widget_type=\"html.default\">\n\t\t\t\t\t\n    <div class=\"cross\" data-position=\"top-left\"><\/div>\n    <div class=\"cross\" data-position=\"top-right\"><\/div>\n    <div class=\"cross\" data-position=\"bottom-left\"><\/div>\n    <div class=\"cross\" data-position=\"bottom-right\"><\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-356136a elementor-widget elementor-widget-heading\" data-id=\"356136a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u015eikayet Nas\u0131l G\u00f6nderilir<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a72e4f e-con-full e-flex e-con e-child\" data-id=\"5a72e4f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-895b9e3 elementor-widget elementor-widget-text-editor\" data-id=\"895b9e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>At EU Internet Ventures (EUIV), we value your experience and take concerns seriously. If something hasn\u2019t met your expectations, we\u2019re here to help make it right. You can submit a complaint free of charge, and we\u2019ll ensure it\u2019s addressed promptly and with care.<\/p>\n<p>You may submit your complaint through the method most convenient for you:\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bb3532 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4bb3532\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:complaints.eu@banxa.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-send-2\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Email: complaints.eu@banxa.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-518de2a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"518de2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-map\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Posta Adresi:<\/strong> <br \/>EU Internet Ventures B.V.<br \/>Nieuwezijds Voorburgwal 162<br \/>1012 SJ Amsterdam<br \/>Hollanda<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f053cf8 elementor-widget elementor-widget-text-editor\" data-id=\"f053cf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>What We Need From You<\/h3>\n<p>Please include your full contact information (name, email, phone number, and address), a brief summary of the issue with any important dates or transaction details, any relevant documents like screenshots or receipts, the name of the crypto-asset service your complaint is about, and a timeline of events.<\/p>\n<h3>What to Expect Next<\/h3>\n<p>We will acknowledge your complaint within 5 business days, provide a full response within 40 business days, notify you if more time is needed (up to 45 business days), and keep you informed throughout.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f43c37a herobtn elementor-widget__width-initial elementor-tablet-align-justify elementor-widget-tablet__width-inherit elementor-widget elementor-widget-button\" data-id=\"f43c37a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/banxa.com\/wp-content\/uploads\/2025\/06\/Complaints-form-EN.pdf\" target=\"_blank\" download=\"\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-document-download\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u015eikayet Formunu \u0130ndir \u0130ngilizce<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09ad902 herobtn elementor-widget__width-initial elementor-tablet-align-justify elementor-mobile-align-justify elementor-widget-tablet__width-inherit elementor-widget elementor-widget-button\" data-id=\"09ad902\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/banxa.com\/wp-content\/uploads\/2025\/06\/Complaints-form-Dutch.pdf\" target=\"_blank\" download=\"\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-document-download\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u015eikayet Formunu \u0130ndir Felemenk\u00e7e<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u015eikayet Nas\u0131l G\u00f6nderilir At EU Internet Ventures (EUIV), we value your experience and take concerns seriously. If something hasn\u2019t met your expectations, we\u2019re here to help make it right. You can submit a complaint free of charge, and we\u2019ll ensure it\u2019s addressed promptly and with care. You may submit your complaint through the method most [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5075","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u015eikayetler - Banxa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/banxa.com\/tr\/sikayetler\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u015eikayetler - Banxa\" \/>\n<meta property=\"og:description\" content=\"\u015eikayet Nas\u0131l G\u00f6nderilir At EU Internet Ventures (EUIV), we value your experience and take concerns seriously. If something hasn\u2019t met your expectations, we\u2019re here to help make it right. You can submit a complaint free of charge, and we\u2019ll ensure it\u2019s addressed promptly and with care. You may submit your complaint through the method most [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/banxa.com\/tr\/sikayetler\/\" \/>\n<meta property=\"og:site_name\" content=\"Banxa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Banxa.Official\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T19:58:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/banxa.com\/wp-content\/uploads\/2025\/04\/Banxa-Holdings-Inc-Cover-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BanxaHoldings\" \/>\n<meta name=\"twitter:label1\" content=\"Tahmini okuma s\u00fcresi\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 dakika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/banxa.com\\\/tr\\\/sikayetler\\\/\",\"url\":\"https:\\\/\\\/banxa.com\\\/tr\\\/sikayetler\\\/\",\"name\":\"\u015eikayetler - Banxa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banxa.com\\\/tr\\\/#website\"},\"datePublished\":\"2025-06-17T02:34:33+00:00\",\"dateModified\":\"2026-04-23T19:58:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/banxa.com\\\/tr\\\/sikayetler\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/banxa.com\\\/tr\\\/sikayetler\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/banxa.com\\\/tr\\\/sikayetler\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/banxa.com\\\/tr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u015eikayetler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/banxa.com\\\/tr\\\/#website\",\"url\":\"https:\\\/\\\/banxa.com\\\/tr\\\/\",\"name\":\"Banxa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/banxa.com\\\/tr\\\/#organization\"},\"alternateName\":\"Banxa Holdings Inc.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/banxa.com\\\/tr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/banxa.com\\\/tr\\\/#organization\",\"name\":\"Banxa\",\"alternateName\":\"Banxa Holdings Inc.\",\"url\":\"https:\\\/\\\/banxa.com\\\/tr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/banxa.com\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/banxa.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Banxa-Icon-RGB-Favicon.png\",\"contentUrl\":\"https:\\\/\\\/banxa.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Banxa-Icon-RGB-Favicon.png\",\"width\":520,\"height\":470,\"caption\":\"Banxa\"},\"image\":{\"@id\":\"https:\\\/\\\/banxa.com\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Banxa.Official\\\/\",\"https:\\\/\\\/x.com\\\/BanxaHoldings\",\"https:\\\/\\\/www.instagram.com\\\/banxaofficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC1ENe9JnShhksGOaMaTyPvQ\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/banxa-com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u015eikayetler - Banxa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/banxa.com\/tr\/sikayetler\/","og_locale":"tr_TR","og_type":"article","og_title":"\u015eikayetler - Banxa","og_description":"\u015eikayet Nas\u0131l G\u00f6nderilir At EU Internet Ventures (EUIV), we value your experience and take concerns seriously. If something hasn\u2019t met your expectations, we\u2019re here to help make it right. You can submit a complaint free of charge, and we\u2019ll ensure it\u2019s addressed promptly and with care. You may submit your complaint through the method most [&hellip;]","og_url":"https:\/\/banxa.com\/tr\/sikayetler\/","og_site_name":"Banxa","article_publisher":"https:\/\/www.facebook.com\/Banxa.Official\/","article_modified_time":"2026-04-23T19:58:06+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/banxa.com\/wp-content\/uploads\/2025\/04\/Banxa-Holdings-Inc-Cover-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@BanxaHoldings","twitter_misc":{"Tahmini okuma s\u00fcresi":"1 dakika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/banxa.com\/tr\/sikayetler\/","url":"https:\/\/banxa.com\/tr\/sikayetler\/","name":"\u015eikayetler - Banxa","isPartOf":{"@id":"https:\/\/banxa.com\/tr\/#website"},"datePublished":"2025-06-17T02:34:33+00:00","dateModified":"2026-04-23T19:58:06+00:00","breadcrumb":{"@id":"https:\/\/banxa.com\/tr\/sikayetler\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/banxa.com\/tr\/sikayetler\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/banxa.com\/tr\/sikayetler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/banxa.com\/tr\/"},{"@type":"ListItem","position":2,"name":"\u015eikayetler"}]},{"@type":"WebSite","@id":"https:\/\/banxa.com\/tr\/#website","url":"https:\/\/banxa.com\/tr\/","name":"Banxa","description":"","publisher":{"@id":"https:\/\/banxa.com\/tr\/#organization"},"alternateName":"Banxa Holdings Inc.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/banxa.com\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Organization","@id":"https:\/\/banxa.com\/tr\/#organization","name":"Banxa","alternateName":"Banxa Holdings Inc.","url":"https:\/\/banxa.com\/tr\/","logo":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/banxa.com\/tr\/#\/schema\/logo\/image\/","url":"https:\/\/banxa.com\/wp-content\/uploads\/2025\/02\/Banxa-Icon-RGB-Favicon.png","contentUrl":"https:\/\/banxa.com\/wp-content\/uploads\/2025\/02\/Banxa-Icon-RGB-Favicon.png","width":520,"height":470,"caption":"Banxa"},"image":{"@id":"https:\/\/banxa.com\/tr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Banxa.Official\/","https:\/\/x.com\/BanxaHoldings","https:\/\/www.instagram.com\/banxaofficial\/","https:\/\/www.youtube.com\/channel\/UC1ENe9JnShhksGOaMaTyPvQ","https:\/\/www.linkedin.com\/company\/banxa-com"]}]}},"_links":{"self":[{"href":"https:\/\/banxa.com\/tr\/wp-json\/wp\/v2\/pages\/5075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/banxa.com\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/banxa.com\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/banxa.com\/tr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/banxa.com\/tr\/wp-json\/wp\/v2\/comments?post=5075"}],"version-history":[{"count":0,"href":"https:\/\/banxa.com\/tr\/wp-json\/wp\/v2\/pages\/5075\/revisions"}],"wp:attachment":[{"href":"https:\/\/banxa.com\/tr\/wp-json\/wp\/v2\/media?parent=5075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}